{"id":5324,"date":"2021-03-15T09:09:12","date_gmt":"2021-03-15T09:09:12","guid":{"rendered":"http:\/\/conex-casting.com\/?page_id=5324"},"modified":"2021-10-23T08:35:44","modified_gmt":"2021-10-23T08:35:44","slug":"raccordi-in-bronzo-per-manichette-antincendio","status":"publish","type":"page","link":"https:\/\/conex-casting.com\/it\/raccordi-in-bronzo-per-manichette-antincendio\/","title":{"rendered":"Raccordi in bronzo per manichette antincendio"},"content":{"rendered":"<p style=\"text-align: center;\"><span style=\"text-decoration: underline; color: #800000; font-size: 18pt;\"><strong>Raccordi in bronzo per manichette antincendio<\/strong><\/span><\/p>\n<p style=\"text-align: center;\"><a class=\"maxbutton-1 maxbutton maxbutton-product-page-button open-popup-modal\"><span class=\"mb-text\">Richiedi un preventivo<\/span><\/a><\/p>\n<p style=\"text-align: justify;\">Conex \u00e8 uno dei maggiori produttori ed esportatori dall&#8217;India di raccordi in bronzo raccordi in bronzo per manichette antincendio fusi con le migliori leghe di rame. I nostri raccordi per tubi flessibili in bronzo con code di tubo in bronzo I raccordi per tubi in bronzo per incendi vengono esportati in tutto il mondo. La nostra gamma di raccordi istantanei per manichette antincendio in bronzo sono utilizzati principalmente dal reparto antincendio per l&#8217;erogazione di acqua al meccanismo antincendio e possono essere utilizzati anche come raccordi per tubi industriali. I giunti istantanei per manichette antincendio hanno una testa del foro nominale di 2 \u00bd &#8220;(maschio o femmina) e terminano con una variet\u00e0 di dimensioni di filettatura femmina parallela (G) BSP, filettatura maschio BSP e code del tubo.<\/p>\n<p style=\"text-align: justify;\">Questi raccordi per manichette antincendio in bronzo o canna di fucile sono fusi nella nostra fonderia di fusione a Jamnagar India da lingotti o billette di bronzo di alta qualit\u00e0 e sono lavorati alla perfezione con i test di pressione richiesti di volta in volta.<\/p>\n<p style=\"text-align: justify;\"><strong>Materiale:<\/strong> Bronzo LG2 Gunmetal (85-5-5-5 rame, zinco, piombo, lega di stagno) ASTM B62, lega UNS C83600, ottone o qualsiasi lega di rame<\/p>\n<p><strong>Discussioni:<\/strong> BSP<\/p>\n<table style=\"border-collapse: collapse; width: 100%;\" border=\"0\">\n<tbody>\n<tr>\n<td style=\"width: 50%;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-5327 size-full\" title=\"Bronze Fire Hose Couplings\" src=\"http:\/\/conex-casting.com\/wp-content\/uploads\/2019\/02\/Bronze-Fire-Hose-Couplings-001.jpg\" alt=\"Bronze Fire Hose Couplings\" width=\"300\" height=\"300\" srcset=\"https:\/\/conex-casting.com\/wp-content\/uploads\/2019\/02\/Bronze-Fire-Hose-Couplings-001.jpg 300w, https:\/\/conex-casting.com\/wp-content\/uploads\/2019\/02\/Bronze-Fire-Hose-Couplings-001-150x150.jpg 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/td>\n<td style=\"width: 50%;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-5328 size-full\" title=\"Bronze Fire Hose Couplings\" src=\"http:\/\/conex-casting.com\/wp-content\/uploads\/2019\/02\/Bronze-Fire-Hose-Couplings-002.jpg\" alt=\"Bronze Fire Hose Couplings\" width=\"300\" height=\"300\" srcset=\"https:\/\/conex-casting.com\/wp-content\/uploads\/2019\/02\/Bronze-Fire-Hose-Couplings-002.jpg 300w, https:\/\/conex-casting.com\/wp-content\/uploads\/2019\/02\/Bronze-Fire-Hose-Couplings-002-150x150.jpg 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Raccordi in bronzo per manichette antincendio Richiedi un preventivo Conex \u00e8 uno dei maggiori produttori ed esportatori dall&#8217;India di raccordi in bronzo raccordi in bronzo per manichette antincendio fusi con le migliori leghe di rame. I nostri raccordi per tubi flessibili in bronzo con code di tubo in bronzo I raccordi per tubi in bronzo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_joinchat":[],"footnotes":""},"class_list":["post-5324","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/conex-casting.com\/it\/wp-json\/wp\/v2\/pages\/5324","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conex-casting.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/conex-casting.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/conex-casting.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/conex-casting.com\/it\/wp-json\/wp\/v2\/comments?post=5324"}],"version-history":[{"count":3,"href":"https:\/\/conex-casting.com\/it\/wp-json\/wp\/v2\/pages\/5324\/revisions"}],"predecessor-version":[{"id":6284,"href":"https:\/\/conex-casting.com\/it\/wp-json\/wp\/v2\/pages\/5324\/revisions\/6284"}],"wp:attachment":[{"href":"https:\/\/conex-casting.com\/it\/wp-json\/wp\/v2\/media?parent=5324"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}